{"id":1001792,"date":"2023-06-15T17:18:59","date_gmt":"2023-06-15T17:18:59","guid":{"rendered":"https:\/\/www.thelashlounge.com\/in-carmel-boardwalk-shoppes\/blog\/drugstore-vs-professional-eyelash-extensions\/"},"modified":"2023-06-22T21:59:39","modified_gmt":"2023-06-22T21:59:39","slug":"drugstore-vs-professional-eyelash-extensions","status":"publish","type":"post","link":"https:\/\/www.thelashlounge.com\/in-carmel-central\/blog\/drugstore-vs-professional-eyelash-extensions\/","title":{"rendered":"Drugstore vs. Professional Eyelash Extensions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":1001796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/posts\/1001792"}],"collection":[{"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/comments?post=1001792"}],"version-history":[{"count":0,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/posts\/1001792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/media\/1001796"}],"wp:attachment":[{"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/media?parent=1001792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/categories?post=1001792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thelashlounge.com\/in-carmel-central\/wp-json\/wp\/v2\/tags?post=1001792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}